{"id":1727,"date":"2018-07-05T16:24:31","date_gmt":"2018-07-05T19:24:31","guid":{"rendered":"https:\/\/www.amerian.com\/devsite\/cordoba-una-ciudad-con-historia\/"},"modified":"2024-11-08T11:40:16","modified_gmt":"2024-11-08T14:40:16","slug":"cordoba-una-ciudad-con-historia","status":"publish","type":"post","link":"https:\/\/www.amerian.com\/en\/cordoba-una-ciudad-con-historia\/","title":{"rendered":"C\u00f3rdoba, una ciudad con historia"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.amerian.com\/wp-content\/uploads\/2024\/04\/canada-cordoba-argentina.png\" style=\"height:400px; width:800px\" \/><br \/>\n<small>Fuente: Shutterstock&nbsp;Vitalii Karas<\/small><\/p>\n<p>El 6 de julio de 1573, el militar y explorador de la conquista Jer&oacute;nimo Luis de Cabrera fund&oacute; la Ciudad de C&oacute;rdoba de la Nueva Andaluc&iacute;a, a orillas, de lo que en aquel entonces, los pueblos sanavirones llamaban el&nbsp; r&iacute;o Quizquizacate. En <a href=\"https:\/\/www.amerian.com\/\">Am&eacute;rian Hoteles<\/a> queremos ense&ntilde;arte y contarte un poco de la incre&iacute;ble historia de esta bella provincia de nuestro pa&iacute;s.&nbsp;<\/p>\n<p>Con un nombre que hac&iacute;a referencia a la ciudad andaluza donde Cabrera hab&iacute;a nacido, el colonizador buscaba establecerse en un punto estrat&eacute;gico que le brindara acceso al Oc&eacute;ano Atl&aacute;ntico. En esa &eacute;poca, los colonos espa&ntilde;oles cre&iacute;an que la Laguna de Mar Chiquita era una bah&iacute;a del mencionado oc&eacute;ano.&nbsp;<\/p>\n<p>Este emplazamiento estrat&eacute;gico permitir&iacute;a a los colonizadores espa&ntilde;oles controlar y gestionar de manera m&aacute;s efectiva sus rutas comerciales mar&iacute;timas y expandir su influencia en la regi&oacute;n. Sin embargo, con el tiempo, se descubri&oacute; que la Laguna de Mar Chiquita no estaba conectada directamente con el oc&eacute;ano, lo que llev&oacute; a una reevaluaci&oacute;n de las estrategias de colonizaci&oacute;n en la zona.<\/p>\n<p>Pero adem&aacute;s de su objetivo estrat&eacute;gico, la fundaci&oacute;n de C&oacute;rdoba estaba ligada a intereses pol&iacute;ticos referidos a la &ldquo;Ciudad de los C&eacute;sares&rdquo;,&nbsp; un paradis&iacute;aco paraje patag&oacute;nico repleto de metales preciosos. Cabrera se asent&oacute; al sur de la jurisdicci&oacute;n que el Virrey del Per&uacute; le hab&iacute;a asignado, solo para estar m&aacute;s cerca de la zona en la que culminar&iacute;a este m&iacute;tico para&iacute;so, hecho de desobediencia por el que fue decapitado en Lima.<\/p>\n<p>&nbsp;<\/p>\n<p>Este a&ntilde;o se cumplen 445 a&ntilde;os de la fundaci&oacute;n de la Ciudad de C&oacute;rdoba. Y a lo largo de estos cuatro siglos, el paso del tiempo modific&oacute; la estructura est&eacute;tica y social de la ciudad hasta transformarla tal como la conocemos hoy.<\/p>\n<p>&nbsp;La infraestructura edilicia de C&oacute;rdoba combina varios estilos arquitect&oacute;nicos que reflejan su rica historia. Se pueden encontrar elementos propios de la &eacute;poca colonial, influencias de la inmigraci&oacute;n del siglo XIX y toques de modernismo del siglo XX. Recorrer las calles de la ciudad es una manera fant&aacute;stica te va a permitir sumergirte en su historia, pero tambi&eacute;n hay puntos de inter&eacute;s y actividades t&iacute;picas que no te pod&eacute;s perder durante tu visita:<\/p>\n<ul>\n<li>\n<p>Centro Hist&oacute;rico: vas a encontrar edificios coloniales, plazas pintorescas y calles empedradas que te transportan al pasado.<\/p>\n<\/li>\n<li>\n<p>Manzana Jesu&iacute;tica: visit&aacute; la Manzana Jesu&iacute;tica, declarada Patrimonio de la Humanidad por la UNESCO, que incluye la Iglesia de la Compa&ntilde;&iacute;a de Jes&uacute;s y la Universidad Nacional de C&oacute;rdoba, entre otros edificios hist&oacute;ricos.<\/p>\n<\/li>\n<li>\n<p>Paseo del Buen Pastor: disfrut&aacute; de este hermoso espacio que combina arquitectura hist&oacute;rica con modernas instalaciones culturales, como exposiciones de arte, espect&aacute;culos en vivo y opciones gastron&oacute;micas.<\/p>\n<\/li>\n<li>\n<p>Mercado Norte: en este lugar vas a encontrar productos frescos, gastronom&iacute;a regional y artesan&iacute;as.<\/p>\n<\/li>\n<li>\n<p>Cerro de la Cruz: sub&iacute; al Cerro de la Cruz para disfrutar de una vista panor&aacute;mica de la ciudad y sus alrededores.<\/p>\n<\/li>\n<li>\n<p>Plaza San Mart&iacute;n: relajate en esta plaza central, rodeada de hermosos edificios hist&oacute;ricos y con una estatua ecuestre del General San Mart&iacute;n en su centro.<\/p>\n<\/li>\n<li>\n<p>Gastronom&iacute;a Cordobesa: conoc&eacute; los platos t&iacute;picos de la regi&oacute;n, como el locro, las empanadas, los alfajores y el tradicional asado argentino.<\/p>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Partamos de la base<\/h2>\n<p><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.amerian.com\/wp-content\/uploads\/2024\/04\/ciudad-de-cordoba-hotel-amerian.png\" style=\"height:400px; width:800px\" \/><\/p>\n<p>A la hora de organizar un tour de referencia, es importante saber cu&aacute;n lejos est&aacute;n los puntos a visitar, del hotel en el que estemos hospedados.<\/p>\n<p>Nosotros te recomendamos <a href=\"https:\/\/www.amerian.com\/hotel\/amerian-cordoba-park-hotel\/\">Am&eacute;rian C&oacute;rdoba Park Hotel<\/a> y <a href=\"https:\/\/www.amerian.com\/hotel\/amerian-executive-cordoba-hotel\/\">Am&eacute;rian Executive C&oacute;rdoba Hotel<\/a>, dos hoteles de nuestra cadena ubicados en la confluencia entre el centro de la ciudad y el barrio de Nueva C&oacute;rdoba. Desde all&iacute;, hay mucho para recorrer, desde centros culturales, museos y paseos hist&oacute;ricos hasta centros comerciales y lugares de gastronom&iacute;a.<\/p>\n<h2>&nbsp;<\/h2>\n<h2>Recorrido hist&oacute;rico<\/h2>\n<p>Frente a nuestros hoteles, sobre el Boulevard San Juan se erige el edificio en el que funcion&oacute; la primera escuela de varones de la Ciudad de C&oacute;rdoba, Jos&eacute; Vicente Olmos. Hoy en d&iacute;a esta construcci&oacute;n de estilo parisino le da vida al Patio Olmos, uno de los centros comerciales m&aacute;s populares de la ciudad. Desde aqu&iacute;, es buena idea comenzar el recorrido.&nbsp;<\/p>\n<p>En direcci&oacute;n norte, al caminar una cuadra por la calle Obispo Trejo, est&aacute; el inicio del &aacute;rea peatonal que rodea a la majestuosa Iglesia de la Compa&ntilde;&iacute;a de Jes&uacute;s. Este templo es un emblema del asentamiento jesuita que data de 1599 en la ciudad. Su imponente arquitectura y su rica historia la convierten en uno de los puntos de inter&eacute;s m&aacute;s destacados de C&oacute;rdoba.<\/p>\n<p>La Iglesia de la Compa&ntilde;&iacute;a de Jes&uacute;s fue declarada Patrimonio de la Humanidad por la UNESCO en el a&ntilde;o 2000, reconociendo su valor cultural e hist&oacute;rico no solo para la ciudad, sino tambi&eacute;n para toda la humanidad. Esta distinci&oacute;n resalta su importancia como un monumento arquitect&oacute;nico excepcional que ha perdurado a lo largo de los siglos.<\/p>\n<p>Considerada una de las iglesias m&aacute;s antiguas de Argentina, la Iglesia de la Compa&ntilde;&iacute;a de Jes&uacute;s es un testimonio vivo de la influencia de la orden jesuita en la regi&oacute;n y su legado en la historia religiosa y cultural del pa&iacute;s. Su visita ofrece una oportunidad &uacute;nica para admirar su impresionante arquitectura barroca y sumergirse en el pasado colonial de C&oacute;rdoba.<\/p>\n<p>A su alrededor, el Colegio Monserrat y el estilo colonial de la calle Caseros, nos ofrecen el &uacute;ltimo pedacito vivo de la Ciudad de C&oacute;rdoba, tal como era en sus inicios.<\/p>\n<p>Desde ah&iacute;, hasta la calle De&aacute;n Funes, el caso hist&oacute;rico toma forma. La zona peatonal nos recibe con el Paseo de las Flores, un pasaje caracter&iacute;stico de la C&oacute;rdoba de los 90&rsquo; ubicado en la Plaza del Fundador Jer&oacute;nimo Luis de Cabrera. Este punto se funde con el paisaje colonial de la Plaza San Mart&iacute;n. El Cabildo Hist&oacute;rico, la Iglesia Catedral y el Teatro Real conforman uno de los puntos m&aacute;s conocidos y transitados de la ciudad.<\/p>\n<p>Desde all&iacute; comienza la zona comercial del centro de C&oacute;rdoba, con la Avenida San Mart&iacute;n y la intersecci&oacute;n de las calles aleda&ntilde;as, mostrando la confluencia de la C&oacute;rdoba de principios del siglo XIX, con el estilo de vida del siglo XX.<\/p>\n<p>Tomando por la izquierda la calle 9 de Julio, nos topamos con la Avenida V&eacute;lez S&aacute;rsfield. Desde all&iacute; podemos retornar hacia nuestro punto de partida. No solo que realizaremos un camino inverso, sino que tomaremos la calle paralela por la que iniciamos el recorrido. All&iacute; se encuentran los edificios en donde funcionaron las primeras universidades de la Ciudad, como idiomas, arquitectura, Ciencias Exactas y el Teatro Libertador de San Mart&iacute;n.<\/p>\n<p>&nbsp;<\/p>\n<h2>El paseo de la Modernidad<\/h2>\n<p>En la esquina de nuestros hoteles, el Boulevard San Juan es intercedido por la Avenida Hip&oacute;lito Irigoyen, un espacio en el que se puede&nbsp; apreciar el inicio de la C&oacute;rdoba Moderna. La amplia avenida nos ofrece excelentes propuestas gastron&oacute;micas y exclusivos locales de compra rodeados de un importante polo empresarial.&nbsp;<\/p>\n<p>Algunas cuadras m&aacute;s arriba nos topamos con el Paseo del Buen Pastor, un espacio cultural en el que antiguamente funcionaba una c&aacute;rcel de mujeres. El show vespertino de aguas danzantes es uno de los fetiches del lugar. &iexcl;Ideal para tomar una merienda y sacarse fotos!<\/p>\n<p>Continuando por el camino, te vas a encontrar con la imponente Iglesia de los Padres Capuchinos, una notable construcci&oacute;n de estilo g&oacute;tico que se alza como un destacado patrimonio hist&oacute;rico de la ciudad. Esta iglesia, con su arquitectura caracter&iacute;stica y su rica historia, es un punto de referencia importante en el paisaje urbano de C&oacute;rdoba.<\/p>\n<p>Adem&aacute;s, en esta zona, se destacan dos importantes espacios culturales:<\/p>\n<ul>\n<li>\n<p>Museo de Antropolog&iacute;a: este museo te ofrece una fascinante mirada a la diversidad cultural de la regi&oacute;n, exhibiendo una amplia colecci&oacute;n de artefactos arqueol&oacute;gicos y etnogr&aacute;ficos que muestran la riqueza y la complejidad de las culturas precolombinas y contempor&aacute;neas de Argentina.<\/p>\n<\/li>\n<li>\n<p>Museo Palacio Ferreryra: ubicado en el antiguo palacio del mismo nombre, este museo alberga una impresionante colecci&oacute;n de arte nacional, con obras de reconocidos artistas nacionales e internacionales. Adem&aacute;s de sus exposiciones permanentes, tambi&eacute;n presenta exhibiciones temporales y actividades culturales diversas.<\/p>\n<\/li>\n<\/ul>\n<p>Estos espacios culturales ofrecen una oportunidad &uacute;nica para sumergirse en el rico patrimonio art&iacute;stico, hist&oacute;rico y cultural de C&oacute;rdoba, permitiendo a los visitantes explorar y apreciar la diversidad y la creatividad de la regi&oacute;n.<\/p>\n<p>Hacia el final de la avenida, la Plaza Espa&ntilde;a nos adentra en el coraz&oacute;n de Nueva C&oacute;rdoba y la movida estudiantil de la Ciudad de C&oacute;rdoba.<\/p>\n<p>&nbsp;<\/p>\n<h2>La propuesta bohemia de la ciudad<\/h2>\n<p>El barrio de Nueva C&oacute;rdoba es caracter&iacute;stico por albergar estudiantes que vienen de otras provincias y pa&iacute;ses a formarse en la Universidad. Los edificios modernos se entremezclan con espacios de recreaci&oacute;n nocturna como boliches y pubs.<\/p>\n<p>Sin embargo, en los &uacute;ltimos a&ntilde;os de esta d&eacute;cada, la movida juvenil se ha expandido hasta G&uuml;emes, un barrio que inicia hacia el otro lado de la ca&ntilde;ada.<\/p>\n<p>Las antiguas estaciones de servicio de este barrio, fueron remodeladas al mejor estilo Soho y hoy son un indiscutido referente del polo gastron&oacute;mico, con propuestas gourmet y fast-food que combinan la elegancia con lo mejor del estilo hippie. Adem&aacute;s, las cervecer&iacute;as artesanales encontraron en este barrio, una tierra cordobesa donde hacer patria.<\/p>\n<p>La cantidad de actividades que se pueden hacer en la Ciudad de C&oacute;rdoba es impresionante y variada. Desde explorar su rica historia y arquitectura hasta disfrutar de su vibrante escena cultural y gastron&oacute;mica, hay algo para todos los gustos y edades. En el d&iacute;a de su aniversario, te invitamos a que la visites y te dejes sorprender por todo lo que tiene para ofrecerte.&nbsp;<\/p>\n<p>Por ejemplo, pod&eacute;s comenzar tu d&iacute;a yendo a los rincones del casco antiguo, visitando las hist&oacute;ricas iglesias y museos que dan testimonio de la rica herencia de la ciudad. Otra posibilidad es recorrer sus calles peatonales, llenas de vida y actividad, donde hay muchos locales, caf&eacute;s y restaurantes que ofrecen lo mejor de la gastronom&iacute;a cordobesa.<\/p>\n<p>No te pierdas la oportunidad de visitar los numerosos parques y espacios verdes de la ciudad, ideales para relajarse y disfrutar del aire libre. Adem&aacute;s, pod&eacute;s asistir a eventos culturales, exposiciones de arte y espect&aacute;culos en vivo que se llevan a cabo en diferentes puntos de la ciudad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada 6 de julio, la Ciudad de C\u00f3rdoba se viste de fiesta para conmemorar su fundaci\u00f3n y a su fundador, Don Jer\u00f3nimo Luis de Cabrera. En este post, hacemos un repaso por su historia y te contamos cu\u00e1les  son los atractivos m\u00e1s caracter\u00edsticos de la ciudad.<\/p>\n","protected":false},"author":2,"featured_media":1731,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[923],"tags":[240,244,239,194,246,196,241,245,243,242],"ubicacion":[47],"localidad":[],"class_list":["post-1727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-efemerides","tag-6-de-julio","tag-casco-historico","tag-codoba","tag-cultura","tag-estudiantes","tag-historia","tag-jeronimo-luis-de-cabrera","tag-nueva-cordoba","tag-plaza-del-fundador","tag-plaza-san-martin","ubicacion-cordoba"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.amerian.com\/en\/wp-json\/wp\/v2\/posts\/1727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amerian.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amerian.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amerian.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amerian.com\/en\/wp-json\/wp\/v2\/comments?post=1727"}],"version-history":[{"count":0,"href":"https:\/\/www.amerian.com\/en\/wp-json\/wp\/v2\/posts\/1727\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amerian.com\/en\/wp-json\/wp\/v2\/media\/1731"}],"wp:attachment":[{"href":"https:\/\/www.amerian.com\/en\/wp-json\/wp\/v2\/media?parent=1727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amerian.com\/en\/wp-json\/wp\/v2\/categories?post=1727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amerian.com\/en\/wp-json\/wp\/v2\/tags?post=1727"},{"taxonomy":"ubicacion","embeddable":true,"href":"https:\/\/www.amerian.com\/en\/wp-json\/wp\/v2\/ubicacion?post=1727"},{"taxonomy":"localidad","embeddable":true,"href":"https:\/\/www.amerian.com\/en\/wp-json\/wp\/v2\/localidad?post=1727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}